{"id":13741,"date":"2019-02-04T17:55:17","date_gmt":"2019-02-04T17:55:17","guid":{"rendered":"https:\/\/africalia.be\/mamounata-nikiema-portrait-d-une-entrepreneuse-engagee-dans-le-cinema\/"},"modified":"2023-08-01T19:01:27","modified_gmt":"2023-08-01T19:01:27","slug":"mamounata-nikiema-portret-van-een-ondernemer-die-zich-inzet-voor-cinema","status":"publish","type":"post","link":"https:\/\/africalia.be\/nl\/mamounata-nikiema-portrait-d-une-entrepreneuse-engagee-dans-le-cinema\/","title":{"rendered":"Mamounata Niki\u00e8ma, portret van een ondernemer die zich inzet voor cinema"},"content":{"rendered":"Form\u00e9e en communication pour le d\u00e9veloppement \u00e0 l\u2019Universit\u00e9 de Ouagadougou, Mamounata Niki\u00e8ma tombe tr\u00e8s vite dans le bain du cin\u00e9ma et se sp\u00e9cialise par l\u2019obtention d\u2018un master 2 en r\u00e9alisation documentaire de cr\u00e9ation en 2008, \u00e0 Saint Louis du S\u00e9n\u00e9gal, mis en place par le programme Africadoc. Apr\u00e8s plusieurs exp\u00e9riences comme r\u00e9alisatrice, de courts m\u00e9trages documentaires et d&rsquo;un moyen m\u00e9trage, elle monte sa propre soci\u00e9t\u00e9 de production, <a href=\"https:\/\/www.facebook.com\/pilumpikuproduction\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><strong>Pilumpiku Production<\/strong><\/a> en 2011. \u00ab En tant que r\u00e9alisatrice, je sentais la n\u00e9cessit\u00e9 qu\u2019il y ait une structure \u00e0 c\u00f4t\u00e9 qui puisse accompagner les porteurs de projets. \u00bb Production de fictions et de documentaires, r\u00e9alisation, organisation de formations, consultations sur des projets, les activit\u00e9s de Pilumpiku sont plurielles, \u00e0 l\u2019image de sa fondatrice qui porte plusieurs casquettes. R\u00e9alisatrice, technicienne de l\u2019image et productrice, Mamounata Niki\u00e8ma n\u2019\u00e9conomise ni son temps ni son \u00e9nergie pour faire exister ce en quoi elle croit : \u00ab (\u2026) je vais dans des rencontres de coproductions, je m\u2019int\u00e9resse \u00e0 des projets et j\u2019accompagne les projets de r\u00e9alisateurs \u00bb. Productrice engag\u00e9e, elle souhaite ardemment r\u00e9pondre \u00e0 un besoin d\u2019accompagnement des professionnels du secteur, et participer ainsi \u00e0 la cr\u00e9ation d\u2019un r\u00e9seau professionnel des auteurs-r\u00e9alisateurs bukinab\u00e8, africains, international. Pilumpiku Production compte plusieurs films \u00e0 son actif : documentaires, s\u00e9ries documentaires et fictions, en co-production avec des pays d\u2019Afrique de l\u2019Ouest en majorit\u00e9, mais aussi avec des partenaires fran\u00e7ais. \n\n<strong>B-Faso Creative, la formation d\u00e9clic<\/strong>\n\nAvec sa casquette de r\u00e9alisatrice, Mamounata Niki\u00e8ma, apr\u00e8s plusieurs courts m\u00e9trages, r\u00e9alise son premier moyen m\u00e9trage \u00ab Savoir Raison Garder \u00bb de 54 minutes en 2011 sur l&rsquo;\u00e9lection pr\u00e9sidentielle de 2010 au Burkina Faso. Elle participe en tant que co-r\u00e9alisatrice, coproductrice et protagoniste dans le film collectif \u00ab Lumi\u00e8re d&rsquo;Octobre \u00bb. Ce film de 75 minutes sorti en 2015 sur le soul\u00e8vement populaire burkinab\u00e8 d&rsquo;octobre 2014 a \u00e9t\u00e9 une coproduction France\/Burkina Faso. En 2015, sous sa casquette de productrice cette fois, elle obtient une aide de 15.000 euros du Fonds Image Francophonie pour la production du film de Marie Laurentine Bayala, \u00ab La lutte continue \u00bb. C\u2019est en v\u00e9ritable entrepreneuse qu\u2019elle d\u00e9cide de postuler au programme <a href=\"https:\/\/africalia.be\/b-faso-creative\/\"><strong>B-Faso Creative<\/strong><\/a> en 2017 : il \u00e9tait temps pour elle de trouver les ailes \u00e0 un projet de magazine, en gestation depuis plusieurs ann\u00e9es.\n\n<figure id=\"attachment_13739\" aria-describedby=\"caption-attachment-13739\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-13739\" src=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled.webp\" alt=\"Mamounata-Nikiema-diplome-B-Faso-creative\" title=\"Mamounata-Nikiema-diplome-B-Faso-creative\" class=\"caption\" align=\"insert|right|credits|taille=grand\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled.webp 2560w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled-300x200.webp 300w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled-1024x683.webp 1024w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled-768x512.webp 768w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled-1536x1024.webp 1536w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled-2048x1366.webp 2048w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled-18x12.webp 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-13739\" class=\"wp-caption-text\">Mamounata-Nikiema-diplome-B-Faso-creative<\/figcaption><\/figure>Enthousiasm\u00e9e par la vari\u00e9t\u00e9 et la qualit\u00e9 des intervenants invit\u00e9s de B-Faso Creative, par leurs connaissances de terrain en prises directes avec ses propres r\u00e9alit\u00e9s, Mamounata Niki\u00e8ma a eu le d\u00e9clic. \u00ab Le module qui m\u2019a beaucoup int\u00e9ress\u00e9 et qui a influenc\u00e9 mon projet tel que je le concevais est le marketing digital. Je pensais mon projet depuis 2014 sous format papier (\u2026) j\u2019ai eu comme un d\u00e9clic. Je me suis dit voil\u00e0 la possibilit\u00e9 de faire na\u00eetre ce projet \u00e0 un co\u00fbt moindre que le support papier, qui co\u00fbte tr\u00e8s cher (\u2026) \u00bb. Son projet est n\u00e9 avec B-Faso Creative : ce sera <a href=\"https:\/\/www.sulunsuku.com\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><strong>Sulunsuku<\/strong><\/a>, une plateforme regroupant des informations du secteur cin\u00e9matographique et audiovisuel au Burkina Faso et en Afrique. Gr\u00e2ce \u00e0 un incitant d\u2019un montant de 3.000 euros, Mamounata lance le d\u00e9veloppement de sa plateforme avec l\u2019aide d\u2019un programmateur et d\u2019un webmaster. Elle rassemble une \u00e9quipe de journalistes et se lance dans la publication d\u2019articles mettant en avant non seulement les parcours de personnalit\u00e9s, mais valorisant \u00e9galement les m\u00e9tiers \u00ab de l\u2019ombre \u00bb, les techniciens notamment, et donnant le micro \u00e0 celles et ceux qui marquent leurs premiers pas de futurs prometteurs. Un r\u00e9pertoire de contacts des professionnels du secteur est en cours d\u2019\u00e9laboration, avec pour objectif de faire valoir les comp\u00e9tences de chacun.e, et ouvrir un espace d\u2019acc\u00e8s \u00e0 des professionnels, afin de sortir d\u2019une logique d\u2019embauche informelle qui privil\u00e9gie le travail par l\u2019interm\u00e9diaire de relations. \u00ab Cette plateforme va permettre de r\u00e9organiser le syst\u00e8me de circulation des opportunit\u00e9s (\u2026) l\u00e0 tu as ton profil avec ton adresse mail o\u00f9 on peut directement t\u2019\u00e9crire, tout le monde peut solliciter tes comp\u00e9tences (\u2026) pour moi quelque part \u00e7a donne plus de chances aux professionnels de travailler. \u00bb A termes, Mamounata souhaite \u00e9galement d\u00e9velopper des services en ligne qui assureront une rentr\u00e9e d\u2019argent via des vid\u00e9os de formation th\u00e9matiques, notamment.\n\n<strong>Une femme engag\u00e9e<\/strong>\n\nLa profession peut compter sur Mamounata Niki\u00e8ma pour faire bouger les choses au Burkina Faso ! Son implication dans le r\u00e9seau cin\u00e9matographique burkinab\u00e9 est infaillible : secr\u00e9taire g\u00e9n\u00e9rale de l\u2019association Africadoc Burkina de 2009 \u00e0 2014, pr\u00e9sidente actuelle de l\u2019Association des Producteurs de Cin\u00e9ma et de l\u2019audiovisuel, membre du r\u00e9pertoire Ouaga Producers Lab, elle fait partager son enthousiasme et son dynamisme \u00e0 tout un secteur d\u2019activit\u00e9. Entrepreneuse et cr\u00e9atrice, Mamounata Niki\u00e8ma fait partie de ses femmes qui ouvrent de nouvelles voies au cin\u00e9ma ind\u00e9pendant africain, et qui trouve un \u00e9cho aupr\u00e8s du public. Preuve en est, \u00ab Au Fant\u00f4me du p\u00e8re \u00bb de Marie Laurentine Bayala, produit par Pilumpiku Production, a \u00e9t\u00e9 r\u00e9compens\u00e9 du Prix du Public au Festival des Identit\u00e9s Culturelles de Ouagadougou en novembre 2018. Un film r\u00e9alis\u00e9 et produit au Burkina Faso, distribu\u00e9 par une entreprise fran\u00e7aise, SUDU CONNEXION, fond\u00e9e par la journaliste franco-burkinab\u00e9 Claire Diao. Mamounata Niki\u00e8ma est actuellement en pleine production de son premier long m\u00e9trage documentaire sur l&rsquo;immigration intitul\u00e9 \u00ab Paris est mon jardin \u00bb, une autre coproduction France\/Burkina Faso. \n\nCr\u00e9ativit\u00e9 et volont\u00e9 d\u2019entreprendre sont dans la place, et les femmes sont en t\u00eate. Bonne suite \u00e0 vous !\n\n[\/par Annabelle Giudice\/]\n\n\n<strong>Lien vers la plateforme Sulunsuku :<\/strong> <a href=\"https:\/\/www.sulunsuku.com\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><strong>https:\/\/www.sulunsuku.com<\/strong><\/a>\n\n<figure id=\"attachment_13740\" aria-describedby=\"caption-attachment-13740\" style=\"width: 1110px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\" size-full wp-image-13740\" src=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/sulunsuku2-jpg.webp\" alt=\"Mamounata-Nikiema-B-Faso-creative-sulunsuku\" title=\"Mamounata-Nikiema-B-Faso-creative-sulunsuku\" class=\"caption\" align=\"insert|left|taille=grand\" width=\"1110\" height=\"689\" srcset=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/sulunsuku2-jpg.webp 1110w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/sulunsuku2-300x186.webp 300w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/sulunsuku2-1024x636.webp 1024w, https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/sulunsuku2-768x477.webp 768w\" sizes=\"(max-width: 1110px) 100vw, 1110px\" \/><figcaption id=\"caption-attachment-13740\" class=\"wp-caption-text\">Mamounata-Nikiema-B-Faso-creative-sulunsuku<\/figcaption><\/figure>\n\n<div id='gallery-1' class='gallery galleryid-13741 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled.webp'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata-diplome-scaled-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Mamounata-Nikiema-diplome-B-Faso-creative\" aria-describedby=\"gallery-1-13742\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-13742'>\n\t\t\t\tMamounata-Nikiema-diplome-B-Faso-creative\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/sulunsuku2-jpg.webp'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/sulunsuku2-150x150.webp\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Mamounata-Nikiema-B-Faso-creative-sulunsuku\" aria-describedby=\"gallery-1-13743\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-13743'>\n\t\t\t\tMamounata-Nikiema-B-Faso-creative-sulunsuku\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<h2 class=\"wp-block-heading\">Documents joints<\/h2>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata_nikiema_portrait_entrepreneuse_engagee_dans_cinema.pdf\">mamounata_nikiema_portrait_entrepreneuse_engagee_dans_cinema<\/a><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>In januari 2018 was Mamounata Niki\u00e8ma, Burkinese regisseur en producent, gepassioneerd ondernemer en onvermoeibare woordvoerder van een cinema die zijn verhaal vertelt vanuit het Afrikaanse continent, een van de drie winnaars van het programma <a href=\"\/nl\/article677.html\/\"><strong>B-Faso creatief<\/strong><\/a>. <\/p>\n<p>B-Faso Creative est un programme pilote lanc\u00e9 par l\u2019asbl Africalia, en collaboration avec l\u2019Ambassade royale du Danemark au Burkina Faso, afin de renforcer les comp\u00e9tences des entrepreneurs des industries culturelles et cr\u00e9atives au Burkina Faso. Mamounata Niki\u00e8ma a \u00e9t\u00e9 soutenue dans son projet de lancement d\u2019une plateforme de cin\u00e9ma et d\u2019audiovisuel, compos\u00e9e de services en ligne \u00e0 destination des professionnels, et d\u2019informations sur l\u2019actualit\u00e9 de ce secteur, accessibles \u00e0 tout public. <\/p>\n<p>Pr\u00e9sentation de la plateforme <a href=\"https:\/\/www.sulunsuku.com\/\"><strong>Sulunsuku<\/strong><\/a>, et de sa cr\u00e9atrice, Mamounata Niki\u00e8ma.<\/p>\n<p>Lisez l\u2019article ci-dessous ou <a href=\"https:\/\/africalia.be\/wp-content\/uploads\/2019\/02\/mamounata_nikiema_portrait_entrepreneuse_engagee_dans_cinema.pdf\"><strong>pdf downloaden<\/strong><\/a>.<\/p>","protected":false},"author":11,"featured_media":13737,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[1018],"tags":[1061,1071,1124,1076],"pays":[1029],"class_list":["post-13741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-agenda","tag-accueil-haut","tag-cinema","tag-digital","tag-entrepreneuriat","pays-burkina-faso"],"acf":[],"_links":{"self":[{"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/posts\/13741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/comments?post=13741"}],"version-history":[{"count":0,"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/posts\/13741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/media\/13737"}],"wp:attachment":[{"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/media?parent=13741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/categories?post=13741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/tags?post=13741"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/africalia.be\/nl\/wp-json\/wp\/v2\/pays?post=13741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}