{"id":13628,"date":"2018-05-02T20:00:00","date_gmt":"2018-05-02T20:00:00","guid":{"rendered":"https:\/\/africalia.be\/slam-poetry-night-we-are-womanists\/"},"modified":"2018-05-02T20:00:00","modified_gmt":"2018-05-02T20:00:00","slug":"slam-poetry-night-we-are-womanists","status":"publish","type":"post","link":"https:\/\/africalia.be\/en\/slam-poetry-night-we-are-womanists\/","title":{"rendered":"Slam Poetry Night: We Are Womanists"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":13627,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"categories":[1041],"tags":[],"pays":[],"class_list":["post-13628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda"],"acf":[],"_links":{"self":[{"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/posts\/13628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/comments?post=13628"}],"version-history":[{"count":0,"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/posts\/13628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/media\/13627"}],"wp:attachment":[{"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/media?parent=13628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/categories?post=13628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/tags?post=13628"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/africalia.be\/en\/wp-json\/wp\/v2\/pays?post=13628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}